{"id":2591,"date":"2014-03-03T12:01:28","date_gmt":"2014-03-03T12:01:28","guid":{"rendered":"http:\/\/www.innoform-coaching.de\/blog\/?p=2591"},"modified":"2014-03-19T08:57:57","modified_gmt":"2014-03-19T08:57:57","slug":"anderung-der-verordnung-eu-nr-102011","status":"publish","type":"post","link":"https:\/\/www.innoform-coaching.de\/blog\/2014\/03\/03\/anderung-der-verordnung-eu-nr-102011\/","title":{"rendered":"\u00c4nderung der Verordnung (EU) Nr. 10\/2011"},"content":{"rendered":"<p>Am 03.03.2014 ist die Verordnung (EU) Nr. 10\/2011 ge\u00e4ndert worden:<br \/>\n<a href=\"http:\/\/eur-lex.europa.eu\/LexUriServ\/LexUriServ.do?uri=OJ:L:2014:062:0013:0015:DE:PDF\">http:\/\/eur-lex.europa.eu\/LexUriServ\/LexUriServ.do?uri=OJ:L:2014:062:0013:0015:DE:PDF<\/a><\/p>\n<p>In erster  Linie wurde die Unionsliste im Anhang 1 \u00fcberarbeitet. Folgende Stoffe  wurden neu aufgenommen oder die Eintragungen ver\u00e4nde<a class=\"edit-timestamp hide-if-no-js\" tabindex=\"4\" href=\"https:\/\/www.innoform-coaching.de\/blog\/wp-admin\/post-new.php#edit_timestamp\"><\/a>rt:<\/p>\n<ul>\n<li>FCM 872: 2-Phenyl-3,3-bis(4-hydroxyphenyl) phthalimidin (CAS 0006607-41-6)<\/li>\n<li>FCM 988: 1,3-Bis(isocyanatomethyl)benzol (CAS 0003634-83-1)<\/li>\n<li>FCM 340: \u00a0Dicyandiamid (CAS 0000461-58-5)<\/li>\n<li>FCM 421: 1,3-Benzoldimethanamin (CAS 0001477-55-0)<\/li>\n<\/ul>\n<p>Zur Begrenzung des Verwaltungsaufwands f\u00fcr Unternehmer sollten  Materialien und Gegenst\u00e4nde aus Kunststoff, die auf Grundlage der  Bestimmungen der Verordnung (EU) Nr. 10\/2011 rechtm\u00e4\u00dfig in Verkehr  gebracht wurden und der vorliegenden Verordnung nicht entsprechen, noch  bis zum 24. M\u00e4rz 2015 in Verkehr gebracht werden d\u00fcrfen. Sie sollten bis  zum Abbau der Best\u00e4nde in Verkehr bleiben d\u00fcrfen.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am 03.03.2014 ist die Verordnung (EU) Nr. 10\/2011 ge\u00e4ndert worden: http:\/\/eur-lex.europa.eu\/LexUriServ\/LexUriServ.do?uri=OJ:L:2014:062:0013:0015:DE:PDF In erster Linie wurde die Unionsliste im Anhang 1 \u00fcberarbeitet. Folgende Stoffe wurden neu aufgenommen oder die Eintragungen ver\u00e4ndert: FCM 872: 2-Phenyl-3,3-bis(4-hydroxyphenyl) phthalimidin (CAS 0006607-41-6) FCM 988: 1,3-Bis(isocyanatomethyl)benzol (CAS 0003634-83-1) FCM 340: \u00a0Dicyandiamid (CAS 0000461-58-5) FCM 421: 1,3-Benzoldimethanamin (CAS 0001477-55-0) Zur Begrenzung des Verwaltungsaufwands [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":2604,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[345,346],"class_list":["post-2591","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-news","tag-unionsliste","tag-verordnung-eu-nr-102011"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Am 03.03.2014 ist die Verordnung (EU) Nr. 10\/2011 ge\u00e4ndert worden: http:\/\/eur-lex.europa.eu\/LexUriServ\/LexUriServ.do?uri=OJ:L:2014:062:0013:0015:DE:PDF In erster Linie wurde die Unionsliste im Anhang 1 \u00fcberarbeitet. Folgende Stoffe wurden neu aufgenommen oder die Eintragungen ver\u00e4ndert: FCM 872: 2-Phenyl-3,3-bis(4-hydroxyphenyl) phthalimidin (CAS 0006607-41-6) FCM 988: 1,3-Bis(isocyanatomethyl)benzol (CAS 0003634-83-1) FCM 340: Dicyandiamid (CAS 0000461-58-5) FCM 421: 1,3-Benzoldimethanamin (CAS 0001477-55-0) Zur Begrenzung des Verwaltungsaufwands\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Karsten Schr\u00f6der\"\/>\n\t<meta name=\"keywords\" content=\"unionsliste,verordnung (eu) nr. 10\/2011,neuigkeiten\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.innoform-coaching.de\/blog\/2014\/03\/03\/anderung-der-verordnung-eu-nr-102011\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Flexpackwissen | Grundwissen und Hintergr\u00fcnde\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u00c4nderung der Verordnung (EU) Nr. 10\/2011 | Flexpackwissen\" \/>\n\t\t<meta property=\"og:description\" content=\"Am 03.03.2014 ist die Verordnung (EU) Nr. 10\/2011 ge\u00e4ndert worden: http:\/\/eur-lex.europa.eu\/LexUriServ\/LexUriServ.do?uri=OJ:L:2014:062:0013:0015:DE:PDF In erster Linie wurde die Unionsliste im Anhang 1 \u00fcberarbeitet. Folgende Stoffe wurden neu aufgenommen oder die Eintragungen ver\u00e4ndert: FCM 872: 2-Phenyl-3,3-bis(4-hydroxyphenyl) phthalimidin (CAS 0006607-41-6) FCM 988: 1,3-Bis(isocyanatomethyl)benzol (CAS 0003634-83-1) FCM 340: Dicyandiamid (CAS 0000461-58-5) FCM 421: 1,3-Benzoldimethanamin (CAS 0001477-55-0) Zur Begrenzung des Verwaltungsaufwands\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.innoform-coaching.de\/blog\/2014\/03\/03\/anderung-der-verordnung-eu-nr-102011\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-03-03T12:01:28+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-03-19T08:57:57+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u00c4nderung der Verordnung (EU) Nr. 10\/2011 | Flexpackwissen\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Am 03.03.2014 ist die Verordnung (EU) Nr. 10\/2011 ge\u00e4ndert worden: http:\/\/eur-lex.europa.eu\/LexUriServ\/LexUriServ.do?uri=OJ:L:2014:062:0013:0015:DE:PDF In erster Linie wurde die Unionsliste im Anhang 1 \u00fcberarbeitet. Folgende Stoffe wurden neu aufgenommen oder die Eintragungen ver\u00e4ndert: FCM 872: 2-Phenyl-3,3-bis(4-hydroxyphenyl) phthalimidin (CAS 0006607-41-6) FCM 988: 1,3-Bis(isocyanatomethyl)benzol (CAS 0003634-83-1) FCM 340: Dicyandiamid (CAS 0000461-58-5) FCM 421: 1,3-Benzoldimethanamin (CAS 0001477-55-0) Zur Begrenzung des Verwaltungsaufwands\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/2014\\\/03\\\/03\\\/anderung-der-verordnung-eu-nr-102011\\\/#article\",\"name\":\"\\u00c4nderung der Verordnung (EU) Nr. 10\\\/2011 | Flexpackwissen\",\"headline\":\"\\u00c4nderung der Verordnung (EU) Nr. 10\\\/2011\",\"author\":{\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/author\\\/ks\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/5812-M1-DLx100-Lugol.jpg\",\"width\":1685,\"height\":1053,\"caption\":\"Schnitt Mehrschichtfolie\"},\"datePublished\":\"2014-03-03T12:01:28+01:00\",\"dateModified\":\"2014-03-19T08:57:57+01:00\",\"inLanguage\":\"de-DE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/2014\\\/03\\\/03\\\/anderung-der-verordnung-eu-nr-102011\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/2014\\\/03\\\/03\\\/anderung-der-verordnung-eu-nr-102011\\\/#webpage\"},\"articleSection\":\"Neuigkeiten, Unionsliste, Verordnung (EU) Nr. 10\\\/2011, Deutsch\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/2014\\\/03\\\/03\\\/anderung-der-verordnung-eu-nr-102011\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/category\\\/news-news\\\/#listItem\",\"name\":\"Neuigkeiten\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/category\\\/news-news\\\/#listItem\",\"position\":2,\"name\":\"Neuigkeiten\",\"item\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/category\\\/news-news\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/2014\\\/03\\\/03\\\/anderung-der-verordnung-eu-nr-102011\\\/#listItem\",\"name\":\"\\u00c4nderung der Verordnung (EU) Nr. 10\\\/2011\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/2014\\\/03\\\/03\\\/anderung-der-verordnung-eu-nr-102011\\\/#listItem\",\"position\":3,\"name\":\"\\u00c4nderung der Verordnung (EU) Nr. 10\\\/2011\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/category\\\/news-news\\\/#listItem\",\"name\":\"Neuigkeiten\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/#organization\",\"name\":\"Innoform Coaching GbR\",\"description\":\"Grundwissen und Hintergr\\u00fcnde\",\"url\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/\",\"telephone\":\"+495405807670\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"Innoform Coaching GbR\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/2014\\\/03\\\/03\\\/anderung-der-verordnung-eu-nr-102011\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/2014\\\/03\\\/03\\\/anderung-der-verordnung-eu-nr-102011\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/author\\\/ks\\\/#author\",\"url\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/author\\\/ks\\\/\",\"name\":\"Karsten Schr\\u00f6der\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/2014\\\/03\\\/03\\\/anderung-der-verordnung-eu-nr-102011\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/39a6617ced6573ac72bcd92a6bae330f619df7af5c34d1872573bbd9607212b1?s=96&d=blank&r=g\",\"width\":96,\"height\":96,\"caption\":\"Karsten Schr\\u00f6der\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/2014\\\/03\\\/03\\\/anderung-der-verordnung-eu-nr-102011\\\/#webpage\",\"url\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/2014\\\/03\\\/03\\\/anderung-der-verordnung-eu-nr-102011\\\/\",\"name\":\"\\u00c4nderung der Verordnung (EU) Nr. 10\\\/2011 | Flexpackwissen\",\"description\":\"Am 03.03.2014 ist die Verordnung (EU) Nr. 10\\\/2011 ge\\u00e4ndert worden: http:\\\/\\\/eur-lex.europa.eu\\\/LexUriServ\\\/LexUriServ.do?uri=OJ:L:2014:062:0013:0015:DE:PDF In erster Linie wurde die Unionsliste im Anhang 1 \\u00fcberarbeitet. Folgende Stoffe wurden neu aufgenommen oder die Eintragungen ver\\u00e4ndert: FCM 872: 2-Phenyl-3,3-bis(4-hydroxyphenyl) phthalimidin (CAS 0006607-41-6) FCM 988: 1,3-Bis(isocyanatomethyl)benzol (CAS 0003634-83-1) FCM 340: Dicyandiamid (CAS 0000461-58-5) FCM 421: 1,3-Benzoldimethanamin (CAS 0001477-55-0) Zur Begrenzung des Verwaltungsaufwands\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/2014\\\/03\\\/03\\\/anderung-der-verordnung-eu-nr-102011\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/author\\\/ks\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/author\\\/ks\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/5812-M1-DLx100-Lugol.jpg\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/2014\\\/03\\\/03\\\/anderung-der-verordnung-eu-nr-102011\\\/#mainImage\",\"width\":1685,\"height\":1053,\"caption\":\"Schnitt Mehrschichtfolie\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/2014\\\/03\\\/03\\\/anderung-der-verordnung-eu-nr-102011\\\/#mainImage\"},\"datePublished\":\"2014-03-03T12:01:28+01:00\",\"dateModified\":\"2014-03-19T08:57:57+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/\",\"name\":\"Flexpackwissen\",\"description\":\"Grundwissen und Hintergr\\u00fcnde\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u00c4nderung der Verordnung (EU) Nr. 10\/2011 | Flexpackwissen","description":"Am 03.03.2014 ist die Verordnung (EU) Nr. 10\/2011 ge\u00e4ndert worden: http:\/\/eur-lex.europa.eu\/LexUriServ\/LexUriServ.do?uri=OJ:L:2014:062:0013:0015:DE:PDF In erster Linie wurde die Unionsliste im Anhang 1 \u00fcberarbeitet. Folgende Stoffe wurden neu aufgenommen oder die Eintragungen ver\u00e4ndert: FCM 872: 2-Phenyl-3,3-bis(4-hydroxyphenyl) phthalimidin (CAS 0006607-41-6) FCM 988: 1,3-Bis(isocyanatomethyl)benzol (CAS 0003634-83-1) FCM 340: Dicyandiamid (CAS 0000461-58-5) FCM 421: 1,3-Benzoldimethanamin (CAS 0001477-55-0) Zur Begrenzung des Verwaltungsaufwands","canonical_url":"https:\/\/www.innoform-coaching.de\/blog\/2014\/03\/03\/anderung-der-verordnung-eu-nr-102011\/","robots":"max-image-preview:large","keywords":"unionsliste,verordnung (eu) nr. 10\/2011,neuigkeiten","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.innoform-coaching.de\/blog\/2014\/03\/03\/anderung-der-verordnung-eu-nr-102011\/#article","name":"\u00c4nderung der Verordnung (EU) Nr. 10\/2011 | Flexpackwissen","headline":"\u00c4nderung der Verordnung (EU) Nr. 10\/2011","author":{"@id":"https:\/\/www.innoform-coaching.de\/blog\/author\/ks\/#author"},"publisher":{"@id":"https:\/\/www.innoform-coaching.de\/blog\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.innoform-coaching.de\/blog\/wp-content\/uploads\/2014\/03\/5812-M1-DLx100-Lugol.jpg","width":1685,"height":1053,"caption":"Schnitt Mehrschichtfolie"},"datePublished":"2014-03-03T12:01:28+01:00","dateModified":"2014-03-19T08:57:57+01:00","inLanguage":"de-DE","mainEntityOfPage":{"@id":"https:\/\/www.innoform-coaching.de\/blog\/2014\/03\/03\/anderung-der-verordnung-eu-nr-102011\/#webpage"},"isPartOf":{"@id":"https:\/\/www.innoform-coaching.de\/blog\/2014\/03\/03\/anderung-der-verordnung-eu-nr-102011\/#webpage"},"articleSection":"Neuigkeiten, Unionsliste, Verordnung (EU) Nr. 10\/2011, Deutsch"},{"@type":"BreadcrumbList","@id":"https:\/\/www.innoform-coaching.de\/blog\/2014\/03\/03\/anderung-der-verordnung-eu-nr-102011\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.innoform-coaching.de\/blog#listItem","position":1,"name":"Home","item":"https:\/\/www.innoform-coaching.de\/blog","nextItem":{"@type":"ListItem","@id":"https:\/\/www.innoform-coaching.de\/blog\/category\/news-news\/#listItem","name":"Neuigkeiten"}},{"@type":"ListItem","@id":"https:\/\/www.innoform-coaching.de\/blog\/category\/news-news\/#listItem","position":2,"name":"Neuigkeiten","item":"https:\/\/www.innoform-coaching.de\/blog\/category\/news-news\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.innoform-coaching.de\/blog\/2014\/03\/03\/anderung-der-verordnung-eu-nr-102011\/#listItem","name":"\u00c4nderung der Verordnung (EU) Nr. 10\/2011"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.innoform-coaching.de\/blog#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.innoform-coaching.de\/blog\/2014\/03\/03\/anderung-der-verordnung-eu-nr-102011\/#listItem","position":3,"name":"\u00c4nderung der Verordnung (EU) Nr. 10\/2011","previousItem":{"@type":"ListItem","@id":"https:\/\/www.innoform-coaching.de\/blog\/category\/news-news\/#listItem","name":"Neuigkeiten"}}]},{"@type":"Organization","@id":"https:\/\/www.innoform-coaching.de\/blog\/#organization","name":"Innoform Coaching GbR","description":"Grundwissen und Hintergr\u00fcnde","url":"https:\/\/www.innoform-coaching.de\/blog\/","telephone":"+495405807670","logo":{"@type":"ImageObject","url":"Innoform Coaching GbR","@id":"https:\/\/www.innoform-coaching.de\/blog\/2014\/03\/03\/anderung-der-verordnung-eu-nr-102011\/#organizationLogo"},"image":{"@id":"https:\/\/www.innoform-coaching.de\/blog\/2014\/03\/03\/anderung-der-verordnung-eu-nr-102011\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.innoform-coaching.de\/blog\/author\/ks\/#author","url":"https:\/\/www.innoform-coaching.de\/blog\/author\/ks\/","name":"Karsten Schr\u00f6der","image":{"@type":"ImageObject","@id":"https:\/\/www.innoform-coaching.de\/blog\/2014\/03\/03\/anderung-der-verordnung-eu-nr-102011\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/39a6617ced6573ac72bcd92a6bae330f619df7af5c34d1872573bbd9607212b1?s=96&d=blank&r=g","width":96,"height":96,"caption":"Karsten Schr\u00f6der"}},{"@type":"WebPage","@id":"https:\/\/www.innoform-coaching.de\/blog\/2014\/03\/03\/anderung-der-verordnung-eu-nr-102011\/#webpage","url":"https:\/\/www.innoform-coaching.de\/blog\/2014\/03\/03\/anderung-der-verordnung-eu-nr-102011\/","name":"\u00c4nderung der Verordnung (EU) Nr. 10\/2011 | Flexpackwissen","description":"Am 03.03.2014 ist die Verordnung (EU) Nr. 10\/2011 ge\u00e4ndert worden: http:\/\/eur-lex.europa.eu\/LexUriServ\/LexUriServ.do?uri=OJ:L:2014:062:0013:0015:DE:PDF In erster Linie wurde die Unionsliste im Anhang 1 \u00fcberarbeitet. Folgende Stoffe wurden neu aufgenommen oder die Eintragungen ver\u00e4ndert: FCM 872: 2-Phenyl-3,3-bis(4-hydroxyphenyl) phthalimidin (CAS 0006607-41-6) FCM 988: 1,3-Bis(isocyanatomethyl)benzol (CAS 0003634-83-1) FCM 340: Dicyandiamid (CAS 0000461-58-5) FCM 421: 1,3-Benzoldimethanamin (CAS 0001477-55-0) Zur Begrenzung des Verwaltungsaufwands","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/www.innoform-coaching.de\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.innoform-coaching.de\/blog\/2014\/03\/03\/anderung-der-verordnung-eu-nr-102011\/#breadcrumblist"},"author":{"@id":"https:\/\/www.innoform-coaching.de\/blog\/author\/ks\/#author"},"creator":{"@id":"https:\/\/www.innoform-coaching.de\/blog\/author\/ks\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.innoform-coaching.de\/blog\/wp-content\/uploads\/2014\/03\/5812-M1-DLx100-Lugol.jpg","@id":"https:\/\/www.innoform-coaching.de\/blog\/2014\/03\/03\/anderung-der-verordnung-eu-nr-102011\/#mainImage","width":1685,"height":1053,"caption":"Schnitt Mehrschichtfolie"},"primaryImageOfPage":{"@id":"https:\/\/www.innoform-coaching.de\/blog\/2014\/03\/03\/anderung-der-verordnung-eu-nr-102011\/#mainImage"},"datePublished":"2014-03-03T12:01:28+01:00","dateModified":"2014-03-19T08:57:57+01:00"},{"@type":"WebSite","@id":"https:\/\/www.innoform-coaching.de\/blog\/#website","url":"https:\/\/www.innoform-coaching.de\/blog\/","name":"Flexpackwissen","description":"Grundwissen und Hintergr\u00fcnde","inLanguage":"de-DE","publisher":{"@id":"https:\/\/www.innoform-coaching.de\/blog\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Flexpackwissen | Grundwissen und Hintergr\u00fcnde","og:type":"article","og:title":"\u00c4nderung der Verordnung (EU) Nr. 10\/2011 | Flexpackwissen","og:description":"Am 03.03.2014 ist die Verordnung (EU) Nr. 10\/2011 ge\u00e4ndert worden: http:\/\/eur-lex.europa.eu\/LexUriServ\/LexUriServ.do?uri=OJ:L:2014:062:0013:0015:DE:PDF In erster Linie wurde die Unionsliste im Anhang 1 \u00fcberarbeitet. Folgende Stoffe wurden neu aufgenommen oder die Eintragungen ver\u00e4ndert: FCM 872: 2-Phenyl-3,3-bis(4-hydroxyphenyl) phthalimidin (CAS 0006607-41-6) FCM 988: 1,3-Bis(isocyanatomethyl)benzol (CAS 0003634-83-1) FCM 340: Dicyandiamid (CAS 0000461-58-5) FCM 421: 1,3-Benzoldimethanamin (CAS 0001477-55-0) Zur Begrenzung des Verwaltungsaufwands","og:url":"https:\/\/www.innoform-coaching.de\/blog\/2014\/03\/03\/anderung-der-verordnung-eu-nr-102011\/","article:published_time":"2014-03-03T12:01:28+00:00","article:modified_time":"2014-03-19T08:57:57+00:00","twitter:card":"summary","twitter:title":"\u00c4nderung der Verordnung (EU) Nr. 10\/2011 | Flexpackwissen","twitter:description":"Am 03.03.2014 ist die Verordnung (EU) Nr. 10\/2011 ge\u00e4ndert worden: http:\/\/eur-lex.europa.eu\/LexUriServ\/LexUriServ.do?uri=OJ:L:2014:062:0013:0015:DE:PDF In erster Linie wurde die Unionsliste im Anhang 1 \u00fcberarbeitet. Folgende Stoffe wurden neu aufgenommen oder die Eintragungen ver\u00e4ndert: FCM 872: 2-Phenyl-3,3-bis(4-hydroxyphenyl) phthalimidin (CAS 0006607-41-6) FCM 988: 1,3-Bis(isocyanatomethyl)benzol (CAS 0003634-83-1) FCM 340: Dicyandiamid (CAS 0000461-58-5) FCM 421: 1,3-Benzoldimethanamin (CAS 0001477-55-0) Zur Begrenzung des Verwaltungsaufwands"},"aioseo_meta_data":{"post_id":"2591","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-01-08 17:09:35","updated":"2022-09-15 15:44:53","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.innoform-coaching.de\/blog\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.innoform-coaching.de\/blog\/category\/news-news\/\" title=\"Neuigkeiten\">Neuigkeiten<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u00c4nderung der Verordnung (EU) Nr. 10\/2011\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.innoform-coaching.de\/blog"},{"label":"Neuigkeiten","link":"https:\/\/www.innoform-coaching.de\/blog\/category\/news-news\/"},{"label":"\u00c4nderung der Verordnung (EU) Nr. 10\/2011","link":"https:\/\/www.innoform-coaching.de\/blog\/2014\/03\/03\/anderung-der-verordnung-eu-nr-102011\/"}],"_links":{"self":[{"href":"https:\/\/www.innoform-coaching.de\/blog\/wp-json\/wp\/v2\/posts\/2591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.innoform-coaching.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.innoform-coaching.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.innoform-coaching.de\/blog\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.innoform-coaching.de\/blog\/wp-json\/wp\/v2\/comments?post=2591"}],"version-history":[{"count":9,"href":"https:\/\/www.innoform-coaching.de\/blog\/wp-json\/wp\/v2\/posts\/2591\/revisions"}],"predecessor-version":[{"id":2597,"href":"https:\/\/www.innoform-coaching.de\/blog\/wp-json\/wp\/v2\/posts\/2591\/revisions\/2597"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.innoform-coaching.de\/blog\/wp-json\/wp\/v2\/media\/2604"}],"wp:attachment":[{"href":"https:\/\/www.innoform-coaching.de\/blog\/wp-json\/wp\/v2\/media?parent=2591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.innoform-coaching.de\/blog\/wp-json\/wp\/v2\/categories?post=2591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.innoform-coaching.de\/blog\/wp-json\/wp\/v2\/tags?post=2591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}