{"id":3107,"date":"2014-11-20T09:50:09","date_gmt":"2014-11-20T09:50:09","guid":{"rendered":"http:\/\/www.innoform-coaching.de\/blog\/?p=3107"},"modified":"2014-12-08T19:00:23","modified_gmt":"2014-12-08T19:00:23","slug":"reststoffboerse-clever-umgesetzt","status":"publish","type":"post","link":"https:\/\/www.innoform-coaching.de\/blog\/2014\/11\/20\/reststoffboerse-clever-umgesetzt\/","title":{"rendered":"Reststoffb\u00f6rse clever umgesetzt"},"content":{"rendered":"<p>Auf der Web-Site: <a href=\"http:\/\/kunststoffenproject.tudelft.nl\/home\" target=\"_blank\">http:\/\/kunststoffenproject.tudelft.nl\/home<\/a> k\u00f6nnen ab sofort Unternehmen ihre Rest-Kunststoffe anbieten oder solche erwerben. Die Seite bietet gratis die M\u00f6glichkeit an, Reststoffe schnell und einfach zum Kauf anzubieten. Der Anbieter kann neben Fotos auch PDF-Dokumente hochladen, um so in gescannter Form \u00fcber die Eigenschaften der Kunststoffe zu informieren. Auf diese Weise findet sich leichter ein K\u00e4ufer, weil das Material anhand seiner Materialwerte eingesch\u00e4tzt werden kann.<\/p>\n<p>Die Website wurde bereits erfolgreich in den Niederlanden eingef\u00fchrt. Das n\u00e4chste Ziel ist, sie auch in Deutschland und Belgien zu etablieren. Sie wurde an der Technischen Universit\u00e4t Delft entwickelt und wird von dort aus betreut. Als Teil des Plastic-Recycling und Re-Use-Platform-Projects* wurde sie durch das European Network Cilmate KIC (Knowledge and Innovation Community) eingerichtet. Ein Teil dieses Projektes besteht darin zu untersuchen, was passiert, wenn Unternehmen der Austausch von Reststoffen erleichtert wird. Der Fokus liegt derzeit auf den Benelux-L\u00e4ndern und Deutschland.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Auf der Web-Site: http:\/\/kunststoffenproject.tudelft.nl\/home k\u00f6nnen ab sofort Unternehmen ihre Rest-Kunststoffe anbieten oder solche erwerben. Die Seite bietet gratis die M\u00f6glichkeit an, Reststoffe schnell und einfach zum Kauf anzubieten. Der Anbieter kann neben Fotos auch PDF-Dokumente hochladen, um so in gescannter Form \u00fcber die Eigenschaften der Kunststoffe zu informieren. Auf diese Weise findet sich leichter ein [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":3108,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3107","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-news"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Auf der Web-Site: http:\/\/kunststoffenproject.tudelft.nl\/home k\u00f6nnen ab sofort Unternehmen ihre Rest-Kunststoffe anbieten oder solche erwerben. Die Seite bietet gratis die M\u00f6glichkeit an, Reststoffe schnell und einfach zum Kauf anzubieten. Der Anbieter kann neben Fotos auch PDF-Dokumente hochladen, um so in gescannter Form \u00fcber die Eigenschaften der Kunststoffe zu informieren. Auf diese Weise findet sich leichter ein\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Karsten Schr\u00f6der\"\/>\n\t<meta name=\"keywords\" content=\"neuigkeiten\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.innoform-coaching.de\/blog\/2014\/11\/20\/reststoffboerse-clever-umgesetzt\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Flexpackwissen | Grundwissen und Hintergr\u00fcnde\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Rohstoffb\u00f6rse f\u00fcr Reststoffe | Flexpackwissen\" \/>\n\t\t<meta property=\"og:description\" content=\"Auf der Web-Site: http:\/\/kunststoffenproject.tudelft.nl\/home k\u00f6nnen ab sofort Unternehmen ihre Rest-Kunststoffe anbieten oder solche erwerben. Die Seite bietet gratis die M\u00f6glichkeit an, Reststoffe schnell und einfach zum Kauf anzubieten. Der Anbieter kann neben Fotos auch PDF-Dokumente hochladen, um so in gescannter Form \u00fcber die Eigenschaften der Kunststoffe zu informieren. Auf diese Weise findet sich leichter ein\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.innoform-coaching.de\/blog\/2014\/11\/20\/reststoffboerse-clever-umgesetzt\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-11-20T09:50:09+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-12-08T19:00:23+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Rohstoffb\u00f6rse f\u00fcr Reststoffe | Flexpackwissen\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Auf der Web-Site: http:\/\/kunststoffenproject.tudelft.nl\/home k\u00f6nnen ab sofort Unternehmen ihre Rest-Kunststoffe anbieten oder solche erwerben. Die Seite bietet gratis die M\u00f6glichkeit an, Reststoffe schnell und einfach zum Kauf anzubieten. Der Anbieter kann neben Fotos auch PDF-Dokumente hochladen, um so in gescannter Form \u00fcber die Eigenschaften der Kunststoffe zu informieren. Auf diese Weise findet sich leichter ein\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/2014\\\/11\\\/20\\\/reststoffboerse-clever-umgesetzt\\\/#article\",\"name\":\"Rohstoffb\\u00f6rse f\\u00fcr Reststoffe | Flexpackwissen\",\"headline\":\"Reststoffb\\u00f6rse clever umgesetzt\",\"author\":{\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/author\\\/ks\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/Polyring.jpg\",\"width\":320,\"height\":119},\"datePublished\":\"2014-11-20T09:50:09+01:00\",\"dateModified\":\"2014-12-08T19:00:23+01:00\",\"inLanguage\":\"de-DE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/2014\\\/11\\\/20\\\/reststoffboerse-clever-umgesetzt\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/2014\\\/11\\\/20\\\/reststoffboerse-clever-umgesetzt\\\/#webpage\"},\"articleSection\":\"Neuigkeiten, Deutsch\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/2014\\\/11\\\/20\\\/reststoffboerse-clever-umgesetzt\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/category\\\/news-news\\\/#listItem\",\"name\":\"Neuigkeiten\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/category\\\/news-news\\\/#listItem\",\"position\":2,\"name\":\"Neuigkeiten\",\"item\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/category\\\/news-news\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/2014\\\/11\\\/20\\\/reststoffboerse-clever-umgesetzt\\\/#listItem\",\"name\":\"Reststoffb\\u00f6rse clever umgesetzt\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/2014\\\/11\\\/20\\\/reststoffboerse-clever-umgesetzt\\\/#listItem\",\"position\":3,\"name\":\"Reststoffb\\u00f6rse clever umgesetzt\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/category\\\/news-news\\\/#listItem\",\"name\":\"Neuigkeiten\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/#organization\",\"name\":\"Innoform Coaching GbR\",\"description\":\"Grundwissen und Hintergr\\u00fcnde\",\"url\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/\",\"telephone\":\"+495405807670\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"Innoform Coaching GbR\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/2014\\\/11\\\/20\\\/reststoffboerse-clever-umgesetzt\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/2014\\\/11\\\/20\\\/reststoffboerse-clever-umgesetzt\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/author\\\/ks\\\/#author\",\"url\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/author\\\/ks\\\/\",\"name\":\"Karsten Schr\\u00f6der\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/2014\\\/11\\\/20\\\/reststoffboerse-clever-umgesetzt\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/39a6617ced6573ac72bcd92a6bae330f619df7af5c34d1872573bbd9607212b1?s=96&d=blank&r=g\",\"width\":96,\"height\":96,\"caption\":\"Karsten Schr\\u00f6der\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/2014\\\/11\\\/20\\\/reststoffboerse-clever-umgesetzt\\\/#webpage\",\"url\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/2014\\\/11\\\/20\\\/reststoffboerse-clever-umgesetzt\\\/\",\"name\":\"Rohstoffb\\u00f6rse f\\u00fcr Reststoffe | Flexpackwissen\",\"description\":\"Auf der Web-Site: http:\\\/\\\/kunststoffenproject.tudelft.nl\\\/home k\\u00f6nnen ab sofort Unternehmen ihre Rest-Kunststoffe anbieten oder solche erwerben. Die Seite bietet gratis die M\\u00f6glichkeit an, Reststoffe schnell und einfach zum Kauf anzubieten. Der Anbieter kann neben Fotos auch PDF-Dokumente hochladen, um so in gescannter Form \\u00fcber die Eigenschaften der Kunststoffe zu informieren. Auf diese Weise findet sich leichter ein\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/2014\\\/11\\\/20\\\/reststoffboerse-clever-umgesetzt\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/author\\\/ks\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/author\\\/ks\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/Polyring.jpg\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/2014\\\/11\\\/20\\\/reststoffboerse-clever-umgesetzt\\\/#mainImage\",\"width\":320,\"height\":119},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/2014\\\/11\\\/20\\\/reststoffboerse-clever-umgesetzt\\\/#mainImage\"},\"datePublished\":\"2014-11-20T09:50:09+01:00\",\"dateModified\":\"2014-12-08T19:00:23+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/\",\"name\":\"Flexpackwissen\",\"description\":\"Grundwissen und Hintergr\\u00fcnde\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Rohstoffb\u00f6rse f\u00fcr Reststoffe | Flexpackwissen","description":"Auf der Web-Site: http:\/\/kunststoffenproject.tudelft.nl\/home k\u00f6nnen ab sofort Unternehmen ihre Rest-Kunststoffe anbieten oder solche erwerben. Die Seite bietet gratis die M\u00f6glichkeit an, Reststoffe schnell und einfach zum Kauf anzubieten. Der Anbieter kann neben Fotos auch PDF-Dokumente hochladen, um so in gescannter Form \u00fcber die Eigenschaften der Kunststoffe zu informieren. Auf diese Weise findet sich leichter ein","canonical_url":"https:\/\/www.innoform-coaching.de\/blog\/2014\/11\/20\/reststoffboerse-clever-umgesetzt\/","robots":"max-image-preview:large","keywords":"neuigkeiten","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.innoform-coaching.de\/blog\/2014\/11\/20\/reststoffboerse-clever-umgesetzt\/#article","name":"Rohstoffb\u00f6rse f\u00fcr Reststoffe | Flexpackwissen","headline":"Reststoffb\u00f6rse clever umgesetzt","author":{"@id":"https:\/\/www.innoform-coaching.de\/blog\/author\/ks\/#author"},"publisher":{"@id":"https:\/\/www.innoform-coaching.de\/blog\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.innoform-coaching.de\/blog\/wp-content\/uploads\/2014\/11\/Polyring.jpg","width":320,"height":119},"datePublished":"2014-11-20T09:50:09+01:00","dateModified":"2014-12-08T19:00:23+01:00","inLanguage":"de-DE","mainEntityOfPage":{"@id":"https:\/\/www.innoform-coaching.de\/blog\/2014\/11\/20\/reststoffboerse-clever-umgesetzt\/#webpage"},"isPartOf":{"@id":"https:\/\/www.innoform-coaching.de\/blog\/2014\/11\/20\/reststoffboerse-clever-umgesetzt\/#webpage"},"articleSection":"Neuigkeiten, Deutsch"},{"@type":"BreadcrumbList","@id":"https:\/\/www.innoform-coaching.de\/blog\/2014\/11\/20\/reststoffboerse-clever-umgesetzt\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.innoform-coaching.de\/blog#listItem","position":1,"name":"Home","item":"https:\/\/www.innoform-coaching.de\/blog","nextItem":{"@type":"ListItem","@id":"https:\/\/www.innoform-coaching.de\/blog\/category\/news-news\/#listItem","name":"Neuigkeiten"}},{"@type":"ListItem","@id":"https:\/\/www.innoform-coaching.de\/blog\/category\/news-news\/#listItem","position":2,"name":"Neuigkeiten","item":"https:\/\/www.innoform-coaching.de\/blog\/category\/news-news\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.innoform-coaching.de\/blog\/2014\/11\/20\/reststoffboerse-clever-umgesetzt\/#listItem","name":"Reststoffb\u00f6rse clever umgesetzt"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.innoform-coaching.de\/blog#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.innoform-coaching.de\/blog\/2014\/11\/20\/reststoffboerse-clever-umgesetzt\/#listItem","position":3,"name":"Reststoffb\u00f6rse clever umgesetzt","previousItem":{"@type":"ListItem","@id":"https:\/\/www.innoform-coaching.de\/blog\/category\/news-news\/#listItem","name":"Neuigkeiten"}}]},{"@type":"Organization","@id":"https:\/\/www.innoform-coaching.de\/blog\/#organization","name":"Innoform Coaching GbR","description":"Grundwissen und Hintergr\u00fcnde","url":"https:\/\/www.innoform-coaching.de\/blog\/","telephone":"+495405807670","logo":{"@type":"ImageObject","url":"Innoform Coaching GbR","@id":"https:\/\/www.innoform-coaching.de\/blog\/2014\/11\/20\/reststoffboerse-clever-umgesetzt\/#organizationLogo"},"image":{"@id":"https:\/\/www.innoform-coaching.de\/blog\/2014\/11\/20\/reststoffboerse-clever-umgesetzt\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.innoform-coaching.de\/blog\/author\/ks\/#author","url":"https:\/\/www.innoform-coaching.de\/blog\/author\/ks\/","name":"Karsten Schr\u00f6der","image":{"@type":"ImageObject","@id":"https:\/\/www.innoform-coaching.de\/blog\/2014\/11\/20\/reststoffboerse-clever-umgesetzt\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/39a6617ced6573ac72bcd92a6bae330f619df7af5c34d1872573bbd9607212b1?s=96&d=blank&r=g","width":96,"height":96,"caption":"Karsten Schr\u00f6der"}},{"@type":"WebPage","@id":"https:\/\/www.innoform-coaching.de\/blog\/2014\/11\/20\/reststoffboerse-clever-umgesetzt\/#webpage","url":"https:\/\/www.innoform-coaching.de\/blog\/2014\/11\/20\/reststoffboerse-clever-umgesetzt\/","name":"Rohstoffb\u00f6rse f\u00fcr Reststoffe | Flexpackwissen","description":"Auf der Web-Site: http:\/\/kunststoffenproject.tudelft.nl\/home k\u00f6nnen ab sofort Unternehmen ihre Rest-Kunststoffe anbieten oder solche erwerben. Die Seite bietet gratis die M\u00f6glichkeit an, Reststoffe schnell und einfach zum Kauf anzubieten. Der Anbieter kann neben Fotos auch PDF-Dokumente hochladen, um so in gescannter Form \u00fcber die Eigenschaften der Kunststoffe zu informieren. Auf diese Weise findet sich leichter ein","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/www.innoform-coaching.de\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.innoform-coaching.de\/blog\/2014\/11\/20\/reststoffboerse-clever-umgesetzt\/#breadcrumblist"},"author":{"@id":"https:\/\/www.innoform-coaching.de\/blog\/author\/ks\/#author"},"creator":{"@id":"https:\/\/www.innoform-coaching.de\/blog\/author\/ks\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.innoform-coaching.de\/blog\/wp-content\/uploads\/2014\/11\/Polyring.jpg","@id":"https:\/\/www.innoform-coaching.de\/blog\/2014\/11\/20\/reststoffboerse-clever-umgesetzt\/#mainImage","width":320,"height":119},"primaryImageOfPage":{"@id":"https:\/\/www.innoform-coaching.de\/blog\/2014\/11\/20\/reststoffboerse-clever-umgesetzt\/#mainImage"},"datePublished":"2014-11-20T09:50:09+01:00","dateModified":"2014-12-08T19:00:23+01:00"},{"@type":"WebSite","@id":"https:\/\/www.innoform-coaching.de\/blog\/#website","url":"https:\/\/www.innoform-coaching.de\/blog\/","name":"Flexpackwissen","description":"Grundwissen und Hintergr\u00fcnde","inLanguage":"de-DE","publisher":{"@id":"https:\/\/www.innoform-coaching.de\/blog\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Flexpackwissen | Grundwissen und Hintergr\u00fcnde","og:type":"article","og:title":"Rohstoffb\u00f6rse f\u00fcr Reststoffe | Flexpackwissen","og:description":"Auf der Web-Site: http:\/\/kunststoffenproject.tudelft.nl\/home k\u00f6nnen ab sofort Unternehmen ihre Rest-Kunststoffe anbieten oder solche erwerben. Die Seite bietet gratis die M\u00f6glichkeit an, Reststoffe schnell und einfach zum Kauf anzubieten. Der Anbieter kann neben Fotos auch PDF-Dokumente hochladen, um so in gescannter Form \u00fcber die Eigenschaften der Kunststoffe zu informieren. Auf diese Weise findet sich leichter ein","og:url":"https:\/\/www.innoform-coaching.de\/blog\/2014\/11\/20\/reststoffboerse-clever-umgesetzt\/","article:published_time":"2014-11-20T09:50:09+00:00","article:modified_time":"2014-12-08T19:00:23+00:00","twitter:card":"summary","twitter:title":"Rohstoffb\u00f6rse f\u00fcr Reststoffe | Flexpackwissen","twitter:description":"Auf der Web-Site: http:\/\/kunststoffenproject.tudelft.nl\/home k\u00f6nnen ab sofort Unternehmen ihre Rest-Kunststoffe anbieten oder solche erwerben. Die Seite bietet gratis die M\u00f6glichkeit an, Reststoffe schnell und einfach zum Kauf anzubieten. Der Anbieter kann neben Fotos auch PDF-Dokumente hochladen, um so in gescannter Form \u00fcber die Eigenschaften der Kunststoffe zu informieren. Auf diese Weise findet sich leichter ein"},"aioseo_meta_data":{"post_id":"3107","title":"Rohstoffb\u00f6rse f\u00fcr Reststoffe | #site_title","description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-01-08 17:09:35","updated":"2022-09-15 16:32:59","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.innoform-coaching.de\/blog\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.innoform-coaching.de\/blog\/category\/news-news\/\" title=\"Neuigkeiten\">Neuigkeiten<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tReststoffb\u00f6rse clever umgesetzt\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.innoform-coaching.de\/blog"},{"label":"Neuigkeiten","link":"https:\/\/www.innoform-coaching.de\/blog\/category\/news-news\/"},{"label":"Reststoffb\u00f6rse clever umgesetzt","link":"https:\/\/www.innoform-coaching.de\/blog\/2014\/11\/20\/reststoffboerse-clever-umgesetzt\/"}],"_links":{"self":[{"href":"https:\/\/www.innoform-coaching.de\/blog\/wp-json\/wp\/v2\/posts\/3107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.innoform-coaching.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.innoform-coaching.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.innoform-coaching.de\/blog\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.innoform-coaching.de\/blog\/wp-json\/wp\/v2\/comments?post=3107"}],"version-history":[{"count":4,"href":"https:\/\/www.innoform-coaching.de\/blog\/wp-json\/wp\/v2\/posts\/3107\/revisions"}],"predecessor-version":[{"id":3117,"href":"https:\/\/www.innoform-coaching.de\/blog\/wp-json\/wp\/v2\/posts\/3107\/revisions\/3117"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.innoform-coaching.de\/blog\/wp-json\/wp\/v2\/media\/3108"}],"wp:attachment":[{"href":"https:\/\/www.innoform-coaching.de\/blog\/wp-json\/wp\/v2\/media?parent=3107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.innoform-coaching.de\/blog\/wp-json\/wp\/v2\/categories?post=3107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.innoform-coaching.de\/blog\/wp-json\/wp\/v2\/tags?post=3107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}