{"id":5991,"date":"2018-02-07T15:07:38","date_gmt":"2018-02-07T15:07:38","guid":{"rendered":"http:\/\/www.innoform-coaching.de\/blog\/?p=5991"},"modified":"2018-02-26T08:05:37","modified_gmt":"2018-02-26T08:05:37","slug":"ralf-seitter","status":"publish","type":"post","link":"https:\/\/www.innoform-coaching.de\/blog\/2018\/02\/07\/ralf-seitter\/","title":{"rendered":"Ralf Seitter zur Dichtheitspr\u00fcfung"},"content":{"rendered":"<div class=\"main\">\n<div>Ralf Seitter ist seit 2002 Gesch\u00e4ftsf\u00fchrer der MRS Seitter GmbH. Er hat tiefgreifende Erfahrung im Vertrieb, Service und in der Kalibrierung von Messger\u00e4ten f\u00fcr Forschung und Qualit\u00e4tssicherung. Die Entwicklung spezieller Applikationen zur Permeationspr\u00fcfung, Verpackungspr\u00fcfung, mechanische Papier- und Folienpr\u00fcfungen und Wasserdampfdurchl\u00e4ssigkeit sowie die Bewertung des Erscheinungsbildes von Oberfl\u00e4chen und Messger\u00e4te f\u00fcr Lacke und Farben geh\u00f6ren zu seinen Kernkompetenzen.<\/div>\n<div>\n<p>Am liebsten besch\u00e4ftigt er sich mit der Bestimmng der Wasserdampfdurchl\u00e4ssigkeit von Baustoffen (auf PE- und PP-Folien) und von Textilien.<\/p>\n<\/div>\n<\/div>\n<p><em><strong>Was hat Sie bewogen, der Einladung von Innoform zu folgen?<\/strong><\/em><\/p>\n<p>Ich bin in regelm\u00e4\u00dfigem losen Kontakt mit Herrn Schr\u00f6der &#8211; wenn man mit kreativen K\u00f6pfen ab und an telefoniert, dann kommt auch ab und an ein Vorschlag zu einem Vortrag dabei heraus.<\/p>\n<p><em><strong>Multilayer ist der Themenschwerpunkt, den das SKZ und Innoform gelegt haben. Was wird Ihre Kernaussage dazu im Rahmen der Tagung sein?<\/strong><\/em><\/p>\n<p>Multilayer ist nicht mein per\u00f6nlicher Schwerpunkt, sondern wie man verschiedene Parameter dieses Werkstoffes pr\u00fcft. Aber generell ist f\u00fcr mich Verpackung nicht b\u00f6se.<\/p>\n<p><em><strong>Sie referieren \u00fcber &#8220;Leckpr\u00fcfung &#8211; Stand der Technik und der Normung&#8221;.\u00a0Worauf sollte man aus Ihrer Sicht bei der Wahl eines Dichtheitspr\u00fcfsystems speziell f\u00fcr Siegeln\u00e4hte achten?<\/strong><\/em><\/p>\n<p>Ich denke, das Ger\u00e4t sollte auf die Verpackung abgestimmt sein, d. h. die Messgrenze sollte den Anforderungen des Produktes an die Verpackung entsprechen. Auch w\u00e4re es sch\u00f6n, wenn das Ger\u00e4t ohne Hochschulabschluss zu bedienen w\u00e4re.<\/p>\n<p>Klar w\u00e4re im Hinblick auf Industrie 4.0 eine vollautomatische und zerst\u00f6rungsfreie 100 %ige Pr\u00fcfung genial, nur werden sich das nur Globalplayer preislich leisten k\u00f6nnen, und auch diese Anlagen sind in der Performance begrenzt. Deshalb liegt mein Schwerpunkt im Bereich Schutzgasverpackungen in einfachen, pr\u00e4zisen Leckpr\u00fcfger\u00e4ten in der \u201cunteren\u201d Preisklasse (unter \u20ac 10.000,-) f\u00fcr kleine und mittlere Betriebe, die bereits Ger\u00e4te zur Messung der Gaskonzentration im Kopfraum der Verpackung (eingedeutscht: Headspaceanalyser) nutzen. Besonders wichtig finde ich, dass das Ger\u00e4t die Leckrate quantifizieren kann und nicht nur schlecht oder gut sagen kann &#8211; dazu mehr in meinem Vortrag.<\/p>\n<p><em><strong>Wo sehen Sie f\u00fcr Folienhersteller und -Verwender besonderes Innovationspotenzial?<\/strong><\/em><\/p>\n<p>In der Senkung des Energie- und Rohstoffverbrauches. Kompostierbare Folien haben ihren Reiz, sollten aber nicht auf Kosten der Lebensmittelerzeugung gehen. Wir haben es mit dem \u201cBio\u201d-Anteil im Sprit gesehen &#8211; es bringt nichts.<\/p>\n<p><em><strong>Wie lassen sich Multilayer und Kreislaufwirtschaft f\u00fcr Ihren Einflussbereich miteinander vereinbaren?<\/strong><\/em><\/p>\n<p>Die Erh\u00f6hung der Mindesthaltbarkeit vermindert Lebensmittelwegwurf &#8211; damit hat der Multilayer schon seinen Dienst erf\u00fcllt, und eine Papierverpackung ist sicher auch nicht \u201cgr\u00fcn\u201d.<\/p>\n<p><em><strong>Innoform bietet technisch orientierte Tagungen an. Besucher sind in der Regel Fachleute aus der Branche, Hersteller und Verwerter. Was erwarten Sie pers\u00f6nlich von der Zuh\u00f6rerschaft?<\/strong><\/em><\/p>\n<p>Ich w\u00fcrde eher sagen, was die Zuh\u00f6rer vom Referenten erwarten d\u00fcrfen: Die Zuh\u00f6rer bezahlen f\u00fcr die Tagung. Daf\u00fcr sollten sie auch korrekte \u201cWare\u201d erhalten, also objektive, informative Vortr\u00e4ge, frei von \u00fcbertriebener (Eigen)Werbung des Referenten.<\/p>\n<p><em><strong>Konferenzen zum Thema \u201eKunststoffe in der Verpackung\u201c erfreuen sich gr\u00f6\u00dferer Beliebtheit. Woher kommt Ihrer Meinung nach dieses gro\u00dfe Interesse an Wissen und auch Kontakten trotz h\u00e4ufig negativer Berichterstattung in den \u00f6ffentlichen Medien?<\/strong><\/em><\/p>\n<p>Vermutlich, weil die Hersteller raus aus der b\u00f6sen Ecke m\u00f6chten &#8211; wobei ja die Ecke nicht b\u00f6se ist. Jeder Ansatz dazu ist willkommen. McDonalds hat es vorgemacht: Das Logo von rot auf gr\u00fcn ge\u00e4ndert &#8230; aber das k\u00f6nnen die Multilayerhersteller besser.<\/p>\n<p><em><strong>Welchen Einfluss haben Ihrer Meinung nach der gesellschaftliche Druck sowie rechtliche Vorgaben und Kundenanforderungen auf die Innovation in der Herstellung von Multilayer-Folien?<\/strong><\/em><\/p>\n<p>Die Entwicklung von \u201cBio&#8221;-Folien &#8211; ob das Sinn macht, kann ich leider nicht beurteilen &#8211; habe aber so meine Bedenken.<\/p>\n<p><em><strong>Wie sch\u00e4tzen Sie auf einer Skala von 1 (sehr gut) bis 5 (schlecht) die Zukunftschancen f\u00fcr Mehrschichtfolien im Vergleich zu anderen Folienarten ein und warum?<\/strong><\/em><\/p>\n<p>Da habe ich ehrlich gesagt keine Ahnung davon.<\/p>\n<p><em><strong>Unsere Teilnehmer m\u00f6chten die Referenten auch gern pers\u00f6nlich besser kennenlernen. Deshalb eine pers\u00f6nliche Frage: Wof\u00fcr begeistern Sie sich neben Ihren beruflichen Aufgaben besonders?<\/strong><\/em><\/p>\n<p>Mountainbike fahren und das Schrauben an Fahrr\u00e4dern generell. Das besch\u00e4ftigt micht zur Zeit am meisten nebenher.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ralf Seitter ist seit 2002 Gesch\u00e4ftsf\u00fchrer der MRS Seitter GmbH. Er hat tiefgreifende Erfahrung im Vertrieb, Service und in der Kalibrierung von Messger\u00e4ten f\u00fcr Forschung und Qualit\u00e4tssicherung. Die Entwicklung spezieller Applikationen zur Permeationspr\u00fcfung, Verpackungspr\u00fcfung, mechanische Papier- und Folienpr\u00fcfungen und Wasserdampfdurchl\u00e4ssigkeit sowie die Bewertung des Erscheinungsbildes von Oberfl\u00e4chen und Messger\u00e4te f\u00fcr Lacke und Farben geh\u00f6ren zu [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":5994,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[670,131,675,3,684,1,686,55,730],"tags":[1892,58,1889,1894,1890,1884,855,1151,876,1896,1886,1891,1895,1885,326,1887,1713,1084,1893,33,197,1883,1882,1897,1888,237],"class_list":["post-5991","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-abfuelltechnik","category-barrierefolien","category-folienherstellung_veredelung","category-folienpruefung","category-primaerverpackungen","category-news-news","category-q-management","category-standbeutel","category-verpackungsdesign","tag-dichtheitspruefsystem","tag-folienhersteller","tag-gaskonzentration","tag-gruen","tag-headspaceanalyser","tag-kalibrierung","tag-kompostierbar","tag-kreislaufwirtschaft","tag-kunststoffe","tag-leckpruefgeraet","tag-leckpruefung","tag-leckrate","tag-mehrschichtfolienflienarten","tag-messgeraete","tag-mindesthaltbarkeit","tag-multilayer","tag-normung","tag-oberflaechen","tag-paperverpackung","tag-permeation","tag-permeationsmessung","tag-pw-04-18","tag-ralf_seitter","tag-rohstoffverbrauch","tag-siegelnaehte","tag-wasserdampfdurchlassigkeit"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Ralf Seitter ist seit 2002 Gesch\u00e4ftsf\u00fchrer der MRS Seitter GmbH. Er hat tiefgreifende Erfahrung im Vertrieb, Service und in der Kalibrierung von Messger\u00e4ten f\u00fcr Forschung und Qualit\u00e4tssicherung. Die Entwicklung spezieller Applikationen zur Permeationspr\u00fcfung, Verpackungspr\u00fcfung, mechanische Papier- und Folienpr\u00fcfungen und Wasserdampfdurchl\u00e4ssigkeit sowie die Bewertung des Erscheinungsbildes von Oberfl\u00e4chen und Messger\u00e4te f\u00fcr Lacke und Farben geh\u00f6ren zu\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Karsten Schr\u00f6der\"\/>\n\t<meta name=\"keywords\" content=\"dichtheitspr\u00fcfsystem,folienhersteller,gaskonzentration,gr\u00fcn,headspaceanalyser,kalibrierung,kompostierbar,kreislaufwirtschaft,kunststoffe,leckpr\u00fcfger\u00e4t,leckpr\u00fcfung,leckrate,mehrschichtfolienflienarten,messger\u00e4te,mindesthaltbarkeit,multilayer,normung,oberfl\u00e4chen,paperverpackung,permeation,permeationsmessung,pw-04-18,ralf_seitter,rohstoffverbrauch,siegeln\u00e4hte,wasserdampfdurchl\u00e4ssigkeit,abf\u00fclltechnik,barrierefolien,folienherstellung\/veredelung,folienpr\u00fcfung &amp; analytik,lebensmittelverpackung,neuigkeiten,q-management\/ hygiene,standbeutel,verpackungsdesign\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.innoform-coaching.de\/blog\/2018\/02\/07\/ralf-seitter\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Flexpackwissen | Grundwissen und Hintergr\u00fcnde\" \/>\n\t\t<meta property=\"og:type\" content=\"activity\" \/>\n\t\t<meta property=\"og:title\" content=\"Ralf Seitter zur Dichtheitspr\u00fcfung | Flexpackwissen\" \/>\n\t\t<meta property=\"og:description\" content=\"Ralf Seitter ist seit 2002 Gesch\u00e4ftsf\u00fchrer der MRS Seitter GmbH. Er hat tiefgreifende Erfahrung im Vertrieb, Service und in der Kalibrierung von Messger\u00e4ten f\u00fcr Forschung und Qualit\u00e4tssicherung. Die Entwicklung spezieller Applikationen zur Permeationspr\u00fcfung, Verpackungspr\u00fcfung, mechanische Papier- und Folienpr\u00fcfungen und Wasserdampfdurchl\u00e4ssigkeit sowie die Bewertung des Erscheinungsbildes von Oberfl\u00e4chen und Messger\u00e4te f\u00fcr Lacke und Farben geh\u00f6ren zu\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.innoform-coaching.de\/blog\/2018\/02\/07\/ralf-seitter\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Ralf Seitter zur Dichtheitspr\u00fcfung | Flexpackwissen\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Ralf Seitter ist seit 2002 Gesch\u00e4ftsf\u00fchrer der MRS Seitter GmbH. Er hat tiefgreifende Erfahrung im Vertrieb, Service und in der Kalibrierung von Messger\u00e4ten f\u00fcr Forschung und Qualit\u00e4tssicherung. Die Entwicklung spezieller Applikationen zur Permeationspr\u00fcfung, Verpackungspr\u00fcfung, mechanische Papier- und Folienpr\u00fcfungen und Wasserdampfdurchl\u00e4ssigkeit sowie die Bewertung des Erscheinungsbildes von Oberfl\u00e4chen und Messger\u00e4te f\u00fcr Lacke und Farben geh\u00f6ren zu\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/2018\\\/02\\\/07\\\/ralf-seitter\\\/#article\",\"name\":\"Ralf Seitter zur Dichtheitspr\\u00fcfung | Flexpackwissen\",\"headline\":\"Ralf Seitter zur Dichtheitspr\\u00fcfung\",\"author\":{\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/author\\\/ks\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/Seitter_Ralf_klein.jpg\",\"width\":113,\"height\":150},\"datePublished\":\"2018-02-07T15:07:38+01:00\",\"dateModified\":\"2018-02-26T08:05:37+01:00\",\"inLanguage\":\"de-DE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/2018\\\/02\\\/07\\\/ralf-seitter\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/2018\\\/02\\\/07\\\/ralf-seitter\\\/#webpage\"},\"articleSection\":\"Abf\\u00fclltechnik, Barrierefolien, Folienherstellung\\\/Veredelung, Folienpr\\u00fcfung &amp; Analytik, Lebensmittelverpackung, Neuigkeiten, Q-Management\\\/ Hygiene, Standbeutel, Verpackungsdesign, Dichtheitspr\\u00fcfsystem, Folienhersteller, Gaskonzentration, gr\\u00fcn, Headspaceanalyser, Kalibrierung, kompostierbar, Kreislaufwirtschaft, Kunststoffe, Leckpr\\u00fcfger\\u00e4t, Leckpr\\u00fcfung, Leckrate, MehrschichtfolienFlienarten, Messger\\u00e4te, Mindesthaltbarkeit, Multilayer, Normung, Oberfl\\u00e4chen, Paperverpackung, Permeation, Permeationsmessung, PW-04-18, Ralf_Seitter, Rohstoffverbrauch, Siegeln\\u00e4hte, Wasserdampfdurchl\\u00e4ssigkeit, Deutsch\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/2018\\\/02\\\/07\\\/ralf-seitter\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/category\\\/news-news\\\/#listItem\",\"name\":\"Neuigkeiten\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/category\\\/news-news\\\/#listItem\",\"position\":2,\"name\":\"Neuigkeiten\",\"item\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/category\\\/news-news\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/2018\\\/02\\\/07\\\/ralf-seitter\\\/#listItem\",\"name\":\"Ralf Seitter zur Dichtheitspr\\u00fcfung\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/2018\\\/02\\\/07\\\/ralf-seitter\\\/#listItem\",\"position\":3,\"name\":\"Ralf Seitter zur Dichtheitspr\\u00fcfung\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/category\\\/news-news\\\/#listItem\",\"name\":\"Neuigkeiten\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/#organization\",\"name\":\"Innoform Coaching GbR\",\"description\":\"Grundwissen und Hintergr\\u00fcnde\",\"url\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/\",\"telephone\":\"+495405807670\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"Innoform Coaching GbR\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/2018\\\/02\\\/07\\\/ralf-seitter\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/2018\\\/02\\\/07\\\/ralf-seitter\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/author\\\/ks\\\/#author\",\"url\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/author\\\/ks\\\/\",\"name\":\"Karsten Schr\\u00f6der\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/2018\\\/02\\\/07\\\/ralf-seitter\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/39a6617ced6573ac72bcd92a6bae330f619df7af5c34d1872573bbd9607212b1?s=96&d=blank&r=g\",\"width\":96,\"height\":96,\"caption\":\"Karsten Schr\\u00f6der\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/2018\\\/02\\\/07\\\/ralf-seitter\\\/#webpage\",\"url\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/2018\\\/02\\\/07\\\/ralf-seitter\\\/\",\"name\":\"Ralf Seitter zur Dichtheitspr\\u00fcfung | Flexpackwissen\",\"description\":\"Ralf Seitter ist seit 2002 Gesch\\u00e4ftsf\\u00fchrer der MRS Seitter GmbH. Er hat tiefgreifende Erfahrung im Vertrieb, Service und in der Kalibrierung von Messger\\u00e4ten f\\u00fcr Forschung und Qualit\\u00e4tssicherung. Die Entwicklung spezieller Applikationen zur Permeationspr\\u00fcfung, Verpackungspr\\u00fcfung, mechanische Papier- und Folienpr\\u00fcfungen und Wasserdampfdurchl\\u00e4ssigkeit sowie die Bewertung des Erscheinungsbildes von Oberfl\\u00e4chen und Messger\\u00e4te f\\u00fcr Lacke und Farben geh\\u00f6ren zu\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/2018\\\/02\\\/07\\\/ralf-seitter\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/author\\\/ks\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/author\\\/ks\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/Seitter_Ralf_klein.jpg\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/2018\\\/02\\\/07\\\/ralf-seitter\\\/#mainImage\",\"width\":113,\"height\":150},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/2018\\\/02\\\/07\\\/ralf-seitter\\\/#mainImage\"},\"datePublished\":\"2018-02-07T15:07:38+01:00\",\"dateModified\":\"2018-02-26T08:05:37+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/\",\"name\":\"Flexpackwissen\",\"description\":\"Grundwissen und Hintergr\\u00fcnde\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.innoform-coaching.de\\\/blog\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Ralf Seitter zur Dichtheitspr\u00fcfung | Flexpackwissen","description":"Ralf Seitter ist seit 2002 Gesch\u00e4ftsf\u00fchrer der MRS Seitter GmbH. Er hat tiefgreifende Erfahrung im Vertrieb, Service und in der Kalibrierung von Messger\u00e4ten f\u00fcr Forschung und Qualit\u00e4tssicherung. Die Entwicklung spezieller Applikationen zur Permeationspr\u00fcfung, Verpackungspr\u00fcfung, mechanische Papier- und Folienpr\u00fcfungen und Wasserdampfdurchl\u00e4ssigkeit sowie die Bewertung des Erscheinungsbildes von Oberfl\u00e4chen und Messger\u00e4te f\u00fcr Lacke und Farben geh\u00f6ren zu","canonical_url":"https:\/\/www.innoform-coaching.de\/blog\/2018\/02\/07\/ralf-seitter\/","robots":"max-image-preview:large","keywords":"dichtheitspr\u00fcfsystem,folienhersteller,gaskonzentration,gr\u00fcn,headspaceanalyser,kalibrierung,kompostierbar,kreislaufwirtschaft,kunststoffe,leckpr\u00fcfger\u00e4t,leckpr\u00fcfung,leckrate,mehrschichtfolienflienarten,messger\u00e4te,mindesthaltbarkeit,multilayer,normung,oberfl\u00e4chen,paperverpackung,permeation,permeationsmessung,pw-04-18,ralf_seitter,rohstoffverbrauch,siegeln\u00e4hte,wasserdampfdurchl\u00e4ssigkeit,abf\u00fclltechnik,barrierefolien,folienherstellung\/veredelung,folienpr\u00fcfung &amp; analytik,lebensmittelverpackung,neuigkeiten,q-management\/ hygiene,standbeutel,verpackungsdesign","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.innoform-coaching.de\/blog\/2018\/02\/07\/ralf-seitter\/#article","name":"Ralf Seitter zur Dichtheitspr\u00fcfung | Flexpackwissen","headline":"Ralf Seitter zur Dichtheitspr\u00fcfung","author":{"@id":"https:\/\/www.innoform-coaching.de\/blog\/author\/ks\/#author"},"publisher":{"@id":"https:\/\/www.innoform-coaching.de\/blog\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.innoform-coaching.de\/blog\/wp-content\/uploads\/2018\/02\/Seitter_Ralf_klein.jpg","width":113,"height":150},"datePublished":"2018-02-07T15:07:38+01:00","dateModified":"2018-02-26T08:05:37+01:00","inLanguage":"de-DE","mainEntityOfPage":{"@id":"https:\/\/www.innoform-coaching.de\/blog\/2018\/02\/07\/ralf-seitter\/#webpage"},"isPartOf":{"@id":"https:\/\/www.innoform-coaching.de\/blog\/2018\/02\/07\/ralf-seitter\/#webpage"},"articleSection":"Abf\u00fclltechnik, Barrierefolien, Folienherstellung\/Veredelung, Folienpr\u00fcfung &amp; Analytik, Lebensmittelverpackung, Neuigkeiten, Q-Management\/ Hygiene, Standbeutel, Verpackungsdesign, Dichtheitspr\u00fcfsystem, Folienhersteller, Gaskonzentration, gr\u00fcn, Headspaceanalyser, Kalibrierung, kompostierbar, Kreislaufwirtschaft, Kunststoffe, Leckpr\u00fcfger\u00e4t, Leckpr\u00fcfung, Leckrate, MehrschichtfolienFlienarten, Messger\u00e4te, Mindesthaltbarkeit, Multilayer, Normung, Oberfl\u00e4chen, Paperverpackung, Permeation, Permeationsmessung, PW-04-18, Ralf_Seitter, Rohstoffverbrauch, Siegeln\u00e4hte, Wasserdampfdurchl\u00e4ssigkeit, Deutsch"},{"@type":"BreadcrumbList","@id":"https:\/\/www.innoform-coaching.de\/blog\/2018\/02\/07\/ralf-seitter\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.innoform-coaching.de\/blog#listItem","position":1,"name":"Home","item":"https:\/\/www.innoform-coaching.de\/blog","nextItem":{"@type":"ListItem","@id":"https:\/\/www.innoform-coaching.de\/blog\/category\/news-news\/#listItem","name":"Neuigkeiten"}},{"@type":"ListItem","@id":"https:\/\/www.innoform-coaching.de\/blog\/category\/news-news\/#listItem","position":2,"name":"Neuigkeiten","item":"https:\/\/www.innoform-coaching.de\/blog\/category\/news-news\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.innoform-coaching.de\/blog\/2018\/02\/07\/ralf-seitter\/#listItem","name":"Ralf Seitter zur Dichtheitspr\u00fcfung"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.innoform-coaching.de\/blog#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.innoform-coaching.de\/blog\/2018\/02\/07\/ralf-seitter\/#listItem","position":3,"name":"Ralf Seitter zur Dichtheitspr\u00fcfung","previousItem":{"@type":"ListItem","@id":"https:\/\/www.innoform-coaching.de\/blog\/category\/news-news\/#listItem","name":"Neuigkeiten"}}]},{"@type":"Organization","@id":"https:\/\/www.innoform-coaching.de\/blog\/#organization","name":"Innoform Coaching GbR","description":"Grundwissen und Hintergr\u00fcnde","url":"https:\/\/www.innoform-coaching.de\/blog\/","telephone":"+495405807670","logo":{"@type":"ImageObject","url":"Innoform Coaching GbR","@id":"https:\/\/www.innoform-coaching.de\/blog\/2018\/02\/07\/ralf-seitter\/#organizationLogo"},"image":{"@id":"https:\/\/www.innoform-coaching.de\/blog\/2018\/02\/07\/ralf-seitter\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.innoform-coaching.de\/blog\/author\/ks\/#author","url":"https:\/\/www.innoform-coaching.de\/blog\/author\/ks\/","name":"Karsten Schr\u00f6der","image":{"@type":"ImageObject","@id":"https:\/\/www.innoform-coaching.de\/blog\/2018\/02\/07\/ralf-seitter\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/39a6617ced6573ac72bcd92a6bae330f619df7af5c34d1872573bbd9607212b1?s=96&d=blank&r=g","width":96,"height":96,"caption":"Karsten Schr\u00f6der"}},{"@type":"WebPage","@id":"https:\/\/www.innoform-coaching.de\/blog\/2018\/02\/07\/ralf-seitter\/#webpage","url":"https:\/\/www.innoform-coaching.de\/blog\/2018\/02\/07\/ralf-seitter\/","name":"Ralf Seitter zur Dichtheitspr\u00fcfung | Flexpackwissen","description":"Ralf Seitter ist seit 2002 Gesch\u00e4ftsf\u00fchrer der MRS Seitter GmbH. Er hat tiefgreifende Erfahrung im Vertrieb, Service und in der Kalibrierung von Messger\u00e4ten f\u00fcr Forschung und Qualit\u00e4tssicherung. Die Entwicklung spezieller Applikationen zur Permeationspr\u00fcfung, Verpackungspr\u00fcfung, mechanische Papier- und Folienpr\u00fcfungen und Wasserdampfdurchl\u00e4ssigkeit sowie die Bewertung des Erscheinungsbildes von Oberfl\u00e4chen und Messger\u00e4te f\u00fcr Lacke und Farben geh\u00f6ren zu","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/www.innoform-coaching.de\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.innoform-coaching.de\/blog\/2018\/02\/07\/ralf-seitter\/#breadcrumblist"},"author":{"@id":"https:\/\/www.innoform-coaching.de\/blog\/author\/ks\/#author"},"creator":{"@id":"https:\/\/www.innoform-coaching.de\/blog\/author\/ks\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.innoform-coaching.de\/blog\/wp-content\/uploads\/2018\/02\/Seitter_Ralf_klein.jpg","@id":"https:\/\/www.innoform-coaching.de\/blog\/2018\/02\/07\/ralf-seitter\/#mainImage","width":113,"height":150},"primaryImageOfPage":{"@id":"https:\/\/www.innoform-coaching.de\/blog\/2018\/02\/07\/ralf-seitter\/#mainImage"},"datePublished":"2018-02-07T15:07:38+01:00","dateModified":"2018-02-26T08:05:37+01:00"},{"@type":"WebSite","@id":"https:\/\/www.innoform-coaching.de\/blog\/#website","url":"https:\/\/www.innoform-coaching.de\/blog\/","name":"Flexpackwissen","description":"Grundwissen und Hintergr\u00fcnde","inLanguage":"de-DE","publisher":{"@id":"https:\/\/www.innoform-coaching.de\/blog\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Flexpackwissen | Grundwissen und Hintergr\u00fcnde","og:type":"activity","og:title":"Ralf Seitter zur Dichtheitspr\u00fcfung | Flexpackwissen","og:description":"Ralf Seitter ist seit 2002 Gesch\u00e4ftsf\u00fchrer der MRS Seitter GmbH. Er hat tiefgreifende Erfahrung im Vertrieb, Service und in der Kalibrierung von Messger\u00e4ten f\u00fcr Forschung und Qualit\u00e4tssicherung. Die Entwicklung spezieller Applikationen zur Permeationspr\u00fcfung, Verpackungspr\u00fcfung, mechanische Papier- und Folienpr\u00fcfungen und Wasserdampfdurchl\u00e4ssigkeit sowie die Bewertung des Erscheinungsbildes von Oberfl\u00e4chen und Messger\u00e4te f\u00fcr Lacke und Farben geh\u00f6ren zu","og:url":"https:\/\/www.innoform-coaching.de\/blog\/2018\/02\/07\/ralf-seitter\/","twitter:card":"summary","twitter:title":"Ralf Seitter zur Dichtheitspr\u00fcfung | Flexpackwissen","twitter:description":"Ralf Seitter ist seit 2002 Gesch\u00e4ftsf\u00fchrer der MRS Seitter GmbH. Er hat tiefgreifende Erfahrung im Vertrieb, Service und in der Kalibrierung von Messger\u00e4ten f\u00fcr Forschung und Qualit\u00e4tssicherung. Die Entwicklung spezieller Applikationen zur Permeationspr\u00fcfung, Verpackungspr\u00fcfung, mechanische Papier- und Folienpr\u00fcfungen und Wasserdampfdurchl\u00e4ssigkeit sowie die Bewertung des Erscheinungsbildes von Oberfl\u00e4chen und Messger\u00e4te f\u00fcr Lacke und Farben geh\u00f6ren zu"},"aioseo_meta_data":{"post_id":"5991","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":"","og_description":"","og_object_type":"activity","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":"","og_article_tags":"","twitter_use_og":false,"twitter_card":"summary","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-01-08 17:15:35","updated":"2022-09-13 20:47:51","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.innoform-coaching.de\/blog\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.innoform-coaching.de\/blog\/category\/news-news\/\" title=\"Neuigkeiten\">Neuigkeiten<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tRalf Seitter zur Dichtheitspr\u00fcfung\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.innoform-coaching.de\/blog"},{"label":"Neuigkeiten","link":"https:\/\/www.innoform-coaching.de\/blog\/category\/news-news\/"},{"label":"Ralf Seitter zur Dichtheitspr\u00fcfung","link":"https:\/\/www.innoform-coaching.de\/blog\/2018\/02\/07\/ralf-seitter\/"}],"_links":{"self":[{"href":"https:\/\/www.innoform-coaching.de\/blog\/wp-json\/wp\/v2\/posts\/5991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.innoform-coaching.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.innoform-coaching.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.innoform-coaching.de\/blog\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.innoform-coaching.de\/blog\/wp-json\/wp\/v2\/comments?post=5991"}],"version-history":[{"count":8,"href":"https:\/\/www.innoform-coaching.de\/blog\/wp-json\/wp\/v2\/posts\/5991\/revisions"}],"predecessor-version":[{"id":6038,"href":"https:\/\/www.innoform-coaching.de\/blog\/wp-json\/wp\/v2\/posts\/5991\/revisions\/6038"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.innoform-coaching.de\/blog\/wp-json\/wp\/v2\/media\/5994"}],"wp:attachment":[{"href":"https:\/\/www.innoform-coaching.de\/blog\/wp-json\/wp\/v2\/media?parent=5991"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.innoform-coaching.de\/blog\/wp-json\/wp\/v2\/categories?post=5991"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.innoform-coaching.de\/blog\/wp-json\/wp\/v2\/tags?post=5991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}